{"id":5856,"date":"2018-12-05T15:01:19","date_gmt":"2018-12-05T15:01:19","guid":{"rendered":"\/blog\/?p=5856"},"modified":"2025-04-01T12:49:59","modified_gmt":"2025-04-01T12:49:59","slug":"3-steps-to-have-a-successful-hour-of-code","status":"publish","type":"post","link":"https:\/\/www.codemonkey.com\/es\/blog\/3-steps-to-have-a-successful-hour-of-code\/","title":{"rendered":"Tres pasos para tener una hora de c\u00f3digo exitosa"},"content":{"rendered":"<p>With <a href=\"https:\/\/www.codemonkey.com\/es\/hour-of-code\/\" target=\"_blank\" rel=\"noopener noreferrer\">La Hora de C\u00f3digo<\/a> and CSEdWeek in full motion, you may be looking for more content to do with your class or are just starting and are not sure where to begin. This guide will help you have a successful Hour of Code in just 3 steps. So how do you get the most out of all the courses offered during Hour of Code? <strong>Primero, decida en qu\u00e9 nivel est\u00e1 su clase, luego utilice los recursos para maestros disponibles y, por \u00faltimo, \u00a1celebre los logros de su clase!<\/strong><\/p>\n<h2>1. Decida el nivel de sus estudiantes<\/h2>\n<p>Code.org ofrece una <a href=\"https:\/\/code.org\/learn\" target=\"_blank\" rel=\"noopener noreferrer\">amplia gama de actividades<\/a> para diferentes niveles, pero podr\u00eda ser dif\u00edcil clasificar todas las actividades para encontrar las mejores para sus estudiantes. Primero, debes pensar en el objetivo de tu Hora del C\u00f3digo: \u00bfes presentar a tu clase la codificaci\u00f3n o es para ayudar a mejorar sus habilidades? Si es para introducir, entonces son principiantes. Si su objetivo es mejorar sus habilidades, entonces su clase es c\u00f3moda. Code.org divide sus actividades en eso: principiante y c\u00f3modo:<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-13793\" src=\"https:\/\/d3sujgifhk94se.cloudfront.net\/wp-content\/uploads\/2018\/12\/10124457\/Hour-of-Code-Activities-CodeMonkey.png\" alt=\"\" width=\"768\" height=\"417\" srcset=\"https:\/\/d3sujgifhk94se.cloudfront.net\/wp-content\/uploads\/2018\/12\/10124457\/Hour-of-Code-Activities-CodeMonkey.png 768w, https:\/\/d3sujgifhk94se.cloudfront.net\/wp-content\/uploads\/2018\/12\/10124457\/Hour-of-Code-Activities-CodeMonkey-300x163.png 300w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<p>Una vez que haya decidido en qu\u00e9 nivel est\u00e1 su clase, haga clic en cualquiera de los botones para luego clasificar las actividades que pueden realizar sus alumnos. Para los principiantes, CodeMonkey recomienda su actividad Coding Adventure donde los estudiantes necesitan ayudar a un mono a atrapar pl\u00e1tanos y es ideal para estudiantes de segundo a sexto grado. Los estudiantes no necesitan ninguna experiencia o introducci\u00f3n a la codificaci\u00f3n para disfrutar de este juego de codificaci\u00f3n basado en texto. Para aquellos que se sientan c\u00f3modos con la codificaci\u00f3n o hayan completado la actividad Coding Adventure, pueden continuar la diversi\u00f3n con Dodo Does Math. Este curso combina los principios de matem\u00e1ticas y codificaci\u00f3n para ayudar a los estudiantes de segundo a cuarto grado a practicar la distancia, la medici\u00f3n y la multiplicaci\u00f3n al ayudar a un Dodo a atrapar sus huevos.<\/p>\n<p>Para aquellos que han aprendido a codificar y completado los 200 desaf\u00edos en Coding Adventure, recomendamos Game Builder, un curso interactivo de dise\u00f1o de juegos para los grados 5-9. Para los maestros de secundaria y preparatoria, recomendamos los cursos m\u00e1s nuevos y avanzados de CodeMonkey: Trivia Chatbot y Moon Lander para los grados 7-10. En Trivia Chatbot, los estudiantes programar\u00e1n un chatbot en Python. En Moon Lander, los estudiantes incorporar\u00e1n principios de dise\u00f1o de juegos para aterrizar de manera segura una nave espacial en la luna usando principios de f\u00edsica y codificaci\u00f3n. <em>Estos son grados recomendados; los estudiantes mayores tambi\u00e9n pueden disfrutar de Coding Adventure.<\/em><\/p>\n<h2>2. Utilice los consejos del maestro<\/h2>\n<p>Hay algunos consejos que siempre debe tener en cuenta al alojar una hora (u horas) de c\u00f3digo.<\/p>\n<p><strong>1.<\/strong> Guardar el progreso de los estudiantes: dado que code.org no requiere que los estudiantes inicien sesi\u00f3n, su progreso no se guarda. Si planea continuar la Hora del C\u00f3digo con sus estudiantes o desea que completen sus cursos por su cuenta, aseg\u00farese de<strong> acceso<\/strong> al programa que est\u00e1 utilizando.<\/p>\n<p><strong>2.<\/strong> Use aud\u00edfonos: distribuya aud\u00edfonos porque las actividades pueden ser ruidosas<\/p>\n<p><strong>3.<\/strong> Planificar Necesidades Tecnol\u00f3gicas:&nbsp;<span style=\"font-weight: 400;\">Puede llevar su clase al laboratorio de computaci\u00f3n por un per\u00edodo para que los estudiantes puedan hacer la Hora del C\u00f3digo juntos. Si su sal\u00f3n de clases ya tiene ChromeBooks, I-pads o carros para laptops, sus estudiantes pueden turnarse para hacer la Hora del C\u00f3digo durante la semana.&nbsp;<\/span><span style=\"font-weight: 400;\">No se preocupe, no necesita una computadora para todos los estudiantes. Trabajar en parejas requiere menos dispositivos y los estudiantes pueden colaborar para aprender m\u00e1s y ayudarse mutuamente.<\/span><\/p>\n<p><strong>4.<\/strong> Compruebe Internet: aseg\u00farese de tener una conexi\u00f3n a Internet activa antes de tiempo, ya que todas las actividades se basan en la web.<\/p>\n<p><strong>5.<\/strong>&nbsp; Consulte las Notas para el maestro: la mayor\u00eda de las actividades tienen notas para el maestro que le brindar\u00e1n soluciones a los desaf\u00edos m\u00e1s dif\u00edciles, un esquema del curso y sugerencias y consejos.<\/p>\n<h2>3. Celebre los logros de la clase<\/h2>\n<p>Introducir a sus estudiantes a las ciencias de la computaci\u00f3n es un paso crucial para allanar su camino hacia un futuro brillante. Durante y despu\u00e9s de CSEdWeek, debe reconocer los esfuerzos de sus estudiantes al compartir el viaje y las fotos de la Hora del C\u00f3digo de sus clases en las redes sociales con #HourOfCode #PlayCodeMonkey. \u00a1No dudes en etiquetarnos en @CodeMonkeySTU! Con mucho gusto compartiremos y retwittearemos. Informe a su comunidad sobre la participaci\u00f3n de sus estudiantes en este movimiento internacional. \u00a1Es algo de lo que estar muy orgulloso! A los padres, familiares y amigos les encantar\u00eda saber que sus estudiantes participaron en esta iniciativa de Ciencias de la Computaci\u00f3n. Aseg\u00farese de imprimir un certificado despu\u00e9s de que completen la Hora del C\u00f3digo.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-13794\" src=\"https:\/\/d3sujgifhk94se.cloudfront.net\/wp-content\/uploads\/2018\/12\/10124512\/CodeMonkey-Certificate1.png\" alt=\"\" width=\"500\" height=\"354\" srcset=\"https:\/\/d3sujgifhk94se.cloudfront.net\/wp-content\/uploads\/2018\/12\/10124512\/CodeMonkey-Certificate1.png 500w, https:\/\/d3sujgifhk94se.cloudfront.net\/wp-content\/uploads\/2018\/12\/10124512\/CodeMonkey-Certificate1-300x212.png 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<h2>Preguntas relacionadas:<\/h2>\n<h3><strong>\u00bfQu\u00e9 es la hora del c\u00f3digo?<\/strong><\/h3>\n<p>La Hora del C\u00f3digo, como su nombre indica, comenz\u00f3 como una lecci\u00f3n introductoria de una hora en Ciencias de la Computaci\u00f3n, enfatizando su importancia en el siglo XXI y demostrando que la programaci\u00f3n de computadoras no es algo que temer, sino que, por el contrario, puede convertirse f\u00e1cilmente en una segunda naturaleza. Hoy, Hour of Code ha pasado de una hora a una iniciativa mundial de una semana de duraci\u00f3n que promueve la programaci\u00f3n inform\u00e1tica. Muchas instituciones, como Microsoft, Apple, Amazon y m\u00e1s, est\u00e1n detr\u00e1s de esta iniciativa. No es un momento en el que los estudiantes est\u00e9n aprendiendo a codificar; principalmente les brinda exposici\u00f3n y acceso para aprender a codificar en un contexto m\u00e1s amplio. Hoy, con todos los cursos disponibles, Hour of Code y CSEdWeek muestran a los estudiantes lo divertido que es la codificaci\u00f3n y abren una ventana para que vean lo divertido e interactivo que puede ser.<\/p>\n<h3><strong>\u00bfPor qu\u00e9 es importante la codificaci\u00f3n?<\/strong><\/h3>\n<p>Aprendiendo a <a href=\"https:\/\/www.codemonkey.com\/es\/blog\/what-are-the-benefits-of-coding-for-kids\/\" target=\"_blank\" rel=\"noopener noreferrer\">el c\u00f3digo beneficia a los ni\u00f1os<\/a> muy. Ayuda a nutrir una variedad de habilidades fundamentales como la creatividad, la l\u00f3gica, el pensamiento cr\u00edtico y las habilidades para la resoluci\u00f3n de problemas. Al ser introducidos a la codificaci\u00f3n desde el principio, los estudiantes pueden prepararse mejor para los desaf\u00edos del siglo XXI. A medida que el uso de la computadora satura cada vez m\u00e1s a la sociedad, depende de los futuros ingenieros innovar y dise\u00f1ar software para mejorar la calidad de vida.<\/p>\n<h3><strong>\u00bfC\u00f3mo puedo continuar con los cursos de Ciencias de la Computaci\u00f3n despu\u00e9s de la Hora del C\u00f3digo?<\/strong><\/h3>\n<p>\u00a1S\u00ed definitivamente! Despu\u00e9s de terminar Hour of Code, puede continuar ense\u00f1ando y aprendiendo con la plataforma en l\u00ednea de CodeMonkey. CodeMonkey ofrece planes de lecciones totalmente guiados, un curso de instructor CodeMonkey y un tablero de aula, donde puede realizar un seguimiento del progreso de los estudiantes y obtener acceso a todos los recursos que necesitar\u00e1 para implementar con \u00e9xito CodeMonkey en su aula.<\/p>\n\n\n<figure class=\"wp-block-embed is-provider-youtube wp-block-embed-youtube\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"What is Hour of Code? | Hour of Code Activities | Free Coding Games and Courses\" width=\"525\" height=\"295\" src=\"https:\/\/www.youtube.com\/embed\/qOa7q-MSCfI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>","protected":false},"excerpt":{"rendered":"<p>With Hour of Code and CSEdWeek in full motion, you may be looking for more content to do with your class or are just starting &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.codemonkey.com\/es\/blog\/3-steps-to-have-a-successful-hour-of-code\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;3 Steps to Have a Successful Hour of Code&#8221;<\/span><\/a><\/p>","protected":false},"author":41,"featured_media":5857,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[744,702,61],"tags":[],"class_list":["post-5856","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-for-teachers","category-hour-of-code","category-tips-hints","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts\/5856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/comments?post=5856"}],"version-history":[{"count":15,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts\/5856\/revisions"}],"predecessor-version":[{"id":19051,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts\/5856\/revisions\/19051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/media\/5857"}],"wp:attachment":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/media?parent=5856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/categories?post=5856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/tags?post=5856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}