{"id":5382,"date":"2018-09-05T12:26:53","date_gmt":"2018-09-05T12:26:53","guid":{"rendered":"\/blog\/?p=5382"},"modified":"2025-04-01T12:51:45","modified_gmt":"2025-04-01T12:51:45","slug":"iste-the-tale-of-a-former-teacher-switching-sides","status":"publish","type":"post","link":"https:\/\/www.codemonkey.com\/es\/blog\/iste-the-tale-of-a-former-teacher-switching-sides\/","title":{"rendered":"ISTE- La historia de un antiguo maestro que cambia de bando"},"content":{"rendered":"<p id=\"016a\" class=\"graf graf--p graf-after--figure\">ISTE 2018- no fue uno para decepcionar. La gran cantidad de sesiones disponibles para los educadores no tiene comparaci\u00f3n con la mayor\u00eda de las conferencias. Las notas clave motivaron e inspiraron todo lo que deber\u00edan ser y m\u00e1s.<\/p>\n<p id=\"1b5e\" class=\"graf graf--p graf-after--p\">Las sesiones, aunque valiosas en mi opini\u00f3n, ni siquiera se comparan con la sala de exposiciones. La sala de exposiciones fue impresionante, llena de innovaciones y color. Cada stand ten\u00eda algo nuevo y emocionante que ofrecer. Microsoft, Google, Kahoot y Pi-top fueron algunos de los stands m\u00e1s atractivos. Estaban llenos de color y llenos de potencial para el pr\u00f3ximo a\u00f1o escolar.<\/p>\n<p id=\"2c34\" class=\"graf graf--p graf-after--p\">Cada a\u00f1o, durante 9 a\u00f1os, pas\u00e9 mis veranos asistiendo a conferencias. Hablando con los innovadores de un sinf\u00edn de empresas de tecnolog\u00eda educativa. Esta vez, este verano estaba del otro lado. Ya no era el maestro. Yo era el expositor. Mi trabajo era tratar de llamar la atenci\u00f3n de los profesores. Sab\u00eda lo que no me gustaba del lado del profesor. Tambi\u00e9n sab\u00eda cuando un profesor no estaba interesado. Observaba a nuestro vendedor hablando con los maestros, pero sab\u00eda c\u00f3mo llegar a los maestros porque yo era uno de ellos. Las horas eran largas, no hab\u00eda almuerzo ni tiempo para descansar. Fue r\u00e1pido y furioso. Mis piernas estaban cansadas y me sent\u00eda casi como un zombi. Mucho entretenimiento que tuvo lugar dentro y fuera del stand. Pero, por primera vez en mucho tiempo, las horas me parecieron valiosas porque sab\u00eda que cre\u00eda en el producto y, al final del d\u00eda, los estudiantes se ver\u00edan afectados.<\/p>\n<p id=\"80d0\" class=\"graf graf--p graf-after--p graf--trailing\">Aprend\u00ed mucho no solo de ser docente sino de ser expositor. Estoy muy agradecido por todos mis a\u00f1os en el sal\u00f3n de clases. S\u00e9 que solo puedo crecer m\u00e1s desde aqu\u00ed.<\/p>\n<p>\u2013Leena Saleh, ex maestra de STEM; Gerente de Desarrollo Profesional en CodeMonkey<\/p>","protected":false},"excerpt":{"rendered":"<p>ISTE 2018- was not one to disappoint. The wealth of sessions available to educators are unparalleled to most conferences. The keynotes were motivating and inspiring &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.codemonkey.com\/es\/blog\/iste-the-tale-of-a-former-teacher-switching-sides\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;ISTE- The Tale of a Former Teacher Switching Sides&#8221;<\/span><\/a><\/p>","protected":false},"author":41,"featured_media":11849,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[744,531],"tags":[],"class_list":["post-5382","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-for-teachers","category-leenas-journey","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts\/5382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/comments?post=5382"}],"version-history":[{"count":1,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts\/5382\/revisions"}],"predecessor-version":[{"id":5385,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/posts\/5382\/revisions\/5385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/media\/11849"}],"wp:attachment":[{"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/media?parent=5382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/categories?post=5382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.codemonkey.com\/es\/wp-json\/wp\/v2\/tags?post=5382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}